{"id":168,"date":"2014-04-11T16:14:39","date_gmt":"2014-04-11T16:14:39","guid":{"rendered":"https:\/\/amigosdeltercertercio.com\/web\/?page_id=168"},"modified":"2015-04-25T13:52:23","modified_gmt":"2015-04-25T13:52:23","slug":"frente-y-retaguardia","status":"publish","type":"page","link":"https:\/\/amigosdeltercertercio.com\/web\/frente-y-retaguardia\/","title":{"rendered":"Frente y Retaguardia"},"content":{"rendered":"<p align=\"center\">ANTECEDENTES: LA VII Y VIII EN LA 2\u00aa LEGION<\/p>\n<p align=\"center\">\n<p align=\"JUSTIFY\"><b>EN EL FRENTE Y EN LA RETAGUARDIA<\/b><\/p>\n<p align=\"JUSTIFY\">Las Especialidades: del granadero al camillero<\/p>\n<p align=\"JUSTIFY\">Y del estilo y la forma de vivir del legionario pasamos al modo de combatir en el frente y de divertirse en la retaguardia. Al igual que ocurre ahora, entonces tambi\u00e9n exist\u00edan <i>especialistas<\/i> en diferentes materias <i>operativas<\/i>. Por supuesto que el <i>fusilero<\/i> constitu\u00eda el pilar b\u00e1sico a la hora de atacar o defender una posici\u00f3n, pero tambi\u00e9n nos aparecen dos combatientes fundamentales en aquella guerra de trincheras, el <i>granadero<\/i> y el <i>ametrallador<\/i>. En cuanto a los apoyos log\u00edsticos, destacaban las figuras del <i>acemilero<\/i>, constantemente tiroteado, y de los <i>camilleros<\/i> corriendo de dos en dos, semiagachados recibiendo tiros sin poder responder al fuego, como sus compa\u00f1eros los fusileros, por tener las manos ocupadas en transportar heridos y muertos. Mejor suerte ten\u00eda el <i>ranchero<\/i>, refugiado un poco m\u00e1s a retaguardia pero con la preocupaci\u00f3n de que las otras armas enemigas, la lluvia y el viento, le permitiesen cocinar la comida que necesitaban sus aguerridos compa\u00f1eros que luchaban en la primera l\u00ednea del frente. El <i>Coronel Mateo<\/i> en su libro la <i>Legi\u00f3n que vive,<\/i> nos descubre as\u00ed a diferentes modelos de legionarios especializados en formas muy distintas de participar en los combates:<\/p>\n<blockquote>\n<blockquote><p><i><\/i><\/p>\n<p align=\"JUSTIFY\"><i><span style=\"font-family: 'Trebuchet MS'; font-size: large;\">\u00abEl fusilero<\/span><\/i><span style=\"font-family: 'Trebuchet MS'; font-size: large;\"> gana las batallas, decide la victoria, defiende los dominios, ocupa los terrenos. \u00c9l compendia en su alma los firmes y serenos valores que se\u00f1alan la ruta de la gloria. La ha escrito las p\u00e1ginas m\u00e1s bellas de la historia con su callado empuje, con sus arranques llenos de tr\u00e1gico hero\u00edsmo, igual a los helenos que trazaron de Esparta la noble ejecutoria. Vigilando de noche, combatiendo de d\u00eda, sus momentos transcurren. Y tiene una alegr\u00eda, que como fuente, nace del sano coraz\u00f3n. En fila tiene un n\u00famero&#8230; Pero apenas es nada. Cuando termina el fuego, cuando el combate acaba, los partes dicen: bajas,<i> tantos <\/i>de la Legi\u00f3n.<\/span><\/p>\n<p align=\"JUSTIFY\"><i>El granadero<\/i> tiene algo del <i>disc\u00f3bolo<\/i> con su gorro cimero. He visto en alg\u00fan friso su hel\u00e9nica figura presta al salto tigresco. Arco de fibra dura que al distenderse lanza la pelota de acero. Va siempre en vanguardia. Desnudo el pecho fiero. El semblante anguloso, sin l\u00ednea de blandura. Donde sienta la paleta, se yergue la estatura amenazante y tr\u00e1gica del bravo granadero. Le entusiasma el mort\u00edfero fragor de sus granadas. Sonr\u00ede ante el silbido de las balas pasadas y el bramar artillero que tiene un ronco son y en un momento el humo le envuelve con su manto. En los que le contemplan hay un temblor de espanto y&#8230; surge de aquel caos un \u00a1viva la Legi\u00f3n.<\/p>\n<p align=\"JUSTIFY\"><i>El ametrallador,<\/i><b> <\/b>cabalgando el sill\u00edn, en el hierro una mano, la diestra en el gatillo e inclinada la testa, hace cantar a su arma la canci\u00f3n de una fiesta guerrera, con un tono viril y sobrehumano. Sus ojos penetrantes vigilan monte y llano y all\u00ed donde algo vivo bulle sobre la cresta lanza el cruel abanico de plomo con que infesta la l\u00ednea roja del horizonte lejano. La m\u00e1quina palpita como una arteria henchida, ruge, canta y solloza, suspira y tiene vida. El legionario, alegre, la sigue en su canci\u00f3n. No le importe el zumbido de abeja de las balas que llevan el dolor y la muerte en sus alas &#8230; hasta que una, golosa, liba en su coraz\u00f3n.<\/p>\n<p align=\"JUSTIFY\"><i>\u00a1 <\/i>El<i> acemilero!<\/i>,<b> <\/b>humilde acemilero legionario, nuestro sost\u00e9n y acomodo. Comida, agua y lecho, t\u00fa los traes!. \u00a1Eres el que m\u00e1s necesitamos y con quien menos hablamos!. Disc\u00falpanos, tu sino es sufrir. \u00a1Eres el perfecto legionario!. La labor de estos legionarios fue abnegada y heroica, ya que el aprovisionamiento de agua y municiones a las posiciones era tarea mortal, y fue corriente el que un litro de agua en primera l\u00ednea lo fuese al precio de varios litros de sangre legionaria. Su labor fue doblemente gloriosa, pues ten\u00eda que luchar contra los moros y contra los resabiados y traicioneros mulos. <i>\u00a1Perm\u00edtame Dios que te mueras y nazcas acemilero!<\/i> Esa es la maldici\u00f3n del acemilero al mulo, desagradecido, arisco y de malas intenciones. El hero\u00edsmo del acemilero era oscuro, al morir sin que nadie se enterase. Los poetas jam\u00e1s cantaron sus haza\u00f1as, s\u00f3lo la de los legionarios que murieron en el combate.<\/p>\n<p align=\"JUSTIFY\"><span style=\"font-family: 'Trebuchet MS'; font-size: large;\">Por su parte, la lucha del ranchero es la le\u00f1a verde y h\u00fameda. El vendaval fustiga y hay que encender la lumbre para hacer el yantar. Los ojos doloridos tienen un lagrimear picante y doloroso que amarga y que castiga. Hay que aviar el rancho, para que no se diga que el ranchero no supo su servicio prestar. Si hay sue\u00f1o, no se duerme. Pecado es descansar mientras los otros marchan, rendidos de fatiga. Humo, grasa, calor de fuego del infierno, agobiador trabajo: es el programa eterno que preside la vida del ranchero en campa\u00f1a. Pero sobre esta vida dura de privaciones, nacen del firme esp\u00edritu las risas y canciones y se brinda con tinto, ya que no con champa\u00f1a.<\/span><\/p>\n<p align=\"JUSTIFY\">Respecto a los <i>camilleros, <\/i>el fundador, en una graf\u00eda picuda, valiosa y decisiva, relata sobre ellos: Son los mejores de la Legi\u00f3n. Representan el esp\u00edritu de compa\u00f1erismo y de abnegaci\u00f3n. En el combate lo m\u00e1s penoso es la quietud; despu\u00e9s de aguantar sin responder. Lo m\u00e1s dif\u00edcil es avanzar, y si se hace fuego o da\u00f1o, de cualquier manera que sea, el camillero sin embargo aguanta el peligro sin contestar a la agresi\u00f3n, sin distraerse y sin dar salida a la tensi\u00f3n nerviosa, que disparando el fusil es calmada como un sedante. En cambio, tiene que avanzar en los momentos de mayor peligro, cuando caen los hombres. \u00a1 Es la verdadera caracter\u00edstica del peligro absoluto!&#8230; Los dem\u00e1s son riesgos relativos, mayores o menores, en donde entra por mucho la imaginaci\u00f3n del protagonista o relator.<\/p>\n<p align=\"JUSTIFY\">El <i>camillero <\/i>ha de dejar su resguardo, adelant\u00e1ndose a la zona de muerte sin poder esquivar su blanco al enemigo que le apunta. Tiene que ir precisamente donde est\u00e1 el ca\u00eddo. Adem\u00e1s, no puede ocultarse como guerrillero aislado, que se echa en el suelo, que se arrodilla y se cubre o disimula con el terreno, con las pe\u00f1as o la vegetaci\u00f3n, reduciendo su silueta o amparando su cuerpo. El camillero no es uno solo, son los dos camilleros unidos por la camilla y retenidos a una marcha pausada, lenta, desesperante en aquellos momentos por el peso de la preciosa carga. Tienen que marchar erguidos y por caminos despejados. Todos los peligros se ciernen sobre ellos. \u00a1As\u00ed caen tantos en la Legi\u00f3n!, \u00a1as\u00ed han muerto tantos!. Los hechos suyos, las haza\u00f1as de los camilleros son bastantes para ellas solas merecer un libro. Avanzar y caer los dos camilleros, salir otra camilla y caer tambi\u00e9n, as\u00ed todos los de la Compa\u00f1\u00eda.<\/p>\n<p align=\"JUSTIFY\"><span style=\"font-family: 'Trebuchet MS'; font-size: xx-small;\"><span style=\"font-family: 'Trebuchet MS'; font-size: large;\">En la Legi\u00f3n hacen juramento especial de sacrificio. Son mirados con predilecto cari\u00f1o. No prestan servicios de guarnici\u00f3n, ni de parapeto; no hacen la limpieza del cuartel. \u00a1 Mucho m\u00e1s merec\u00edan! Los pod\u00e9is conocer: llevan un brazalete con la insignia de la Cruz Roja\u00bb.<\/span><\/span><\/p>\n<\/blockquote>\n<\/blockquote>\n<p align=\"JUSTIFY\">Las Madrinas de Guerra: cartas de amor<\/p>\n<p align=\"JUSTIFY\">Cuando tras unos d\u00edas o meses de lucha en el frente se regresaba a los campamentos base, a los legionarios les esperaban las <i>cartas <\/i>de las esposas o de las <i>madrinas de guerra<\/i>. Hay que tener en cuenta que entonces no exist\u00edan ni <i>televisores<\/i> ni siquiera <i>transistores<\/i> para escuchar las noticias o ver una pel\u00edcula. La carta era la moda del momento y para los que no sab\u00edan leer ni escribir siempre les quedaba el recurso de recurrir a la ayuda del compa\u00f1ero <i>letrado.<\/i><\/p>\n<p align=\"JUSTIFY\"><span style=\"font-family: 'Trebuchet MS'; font-size: large;\">Las <i>madrinas de guerra<\/i>, adquirieron desde los tiempos fundacionales un auge extraordinario. Raro era el legionario que no tuviera una corresponsal, y algunos, tres, cuatro o m\u00e1s. Para aquellos hombres no comunes, que viv\u00edan perpetuamente en el campo, entre privaciones y riesgos, sin relaci\u00f3n personal alguna con el mundo, que llevaban sobre s\u00ed el bagaje de tantas tragedias o comedias del pasado, era un inquieto placer esperar el toque de correo. Y cuando sonaban las cornetas anunci\u00e1ndolo, acud\u00edan en enjambre a recoger las misivas. Despu\u00e9s, \u00a1cu\u00e1ntas horas de asueto dedicadas a escribir!, \u00a1cu\u00e1ntas dulces mentiras cuajadas de ilusi\u00f3n!, \u00a1cu\u00e1ntas ternezas seg\u00fan la relaci\u00f3n epistolar iban adquiriendo calor, entusiasmo, para un amor imposible!. Sobre ellas, la firme mano de <i>Mill\u00e1n Astray<\/i> escribi\u00f3, con su letra grande:<\/span><\/p>\n<blockquote>\n<blockquote>\n<p align=\"JUSTIFY\">\u00abUn desbordamiento de piedad las impulsa, acompa\u00f1ado de c\u00e1lido patriotismo; el amor las alumbra y gu\u00eda, y es tambi\u00e9n la braveza, que las pide compartir las penas y peligros de la guerra. Unos puntitos de romanticismo aroman el ambiente en que respiran, y el encanto de lo desconocido, todos los legionarios est\u00e1n a vuestros pies y todos esperan vuestras cartas!. En La Legi\u00f3n, las madrinas de guerra ocupan el lugar preferente. Los legionarios son dados a las escrituras; abundan los sentimentales y los poetas; las horas de campamento, al caer la tarde, cuando cesan los trabajos, son largas; el blocao o la posici\u00f3n avanzada invitan a escribir y a pensar en las madrinas.<\/p>\n<p align=\"JUSTIFY\">Nuestros hombres se agencian madrinazgos con facilidad; tambi\u00e9n le favorece el que son distinguidos por la gentil congregaci\u00f3n madrinista. Muchas se dirigen al Jefe o a los Oficiales pidi\u00e9ndoles ahijados, y con encanto se las sirve, procurando que coincida con sus predilecciones. Algunas env\u00edan de antemano su retrato, y es lo cierto que todas son bellas.<\/p>\n<p align=\"JUSTIFY\">Los Oficiales son aficionad\u00edsimos; algunos, avaros de madrinas, tienen varias y llevan la correspondencia como si fuesen un sacerdocio. No faltan entre ellos, y lo mismo en los legionarios, quienes cuentan aventuras, hero\u00edsmos, sucesos fant\u00e1sticos con que interesar a las madrinas, y tambi\u00e9n les env\u00edan fotograf\u00edas propias o ajenas, si el que suplanta tiene mejor tipo. Otros hacen carreras fabulosas y cada dos meses notifican a la madrina un nuevo ascenso. \u00a1 Es que hay el que se ofreci\u00f3 como soldado y era Oficial y puede permitirse el lujo de ir ascendiendo hasta llegar a la estrella que, galante, pone a los pies de la que, ya pasada esa \u00e9poca, es la due\u00f1a de sus pensamientos. Algunos formalizan la correspondencia y se convierten en serios amor\u00edos que terminan en feliz boda.<\/p>\n<p align=\"JUSTIFY\">En fin, madrinitas de guerra, seguid acudiendo a la llamada de los sedientos de un cari\u00f1o. Creedles poco cuando relaten emocionantes haza\u00f1as de las que son protagonistas. Enviadles de vez en cuando alg\u00fan regalito y desconfiad de las fotograf\u00edas, sin perder la esperanza de que el ahijado aumente el parentesco, si es que as\u00ed lo dese\u00e1is\u00bb.<\/p>\n<\/blockquote>\n<\/blockquote>\n<p align=\"JUSTIFY\">El ocio en retaguardia: las cantineras<\/p>\n<p align=\"JUSTIFY\">Pero en los campamentos de la retaguardia no s\u00f3lo les esperaban a los legionarios las cartas de las esposas o de las madrinas de guerra. Se comprende que aquellos j\u00f3venes que d\u00eda a d\u00eda arriesgaban su vida y ve\u00edan de cerca la muerte se alegrasen de contemplar, hablar, o incluso mantener relaciones \u00edntimas con mujeres. Benditas mujeres aquellas con las que so\u00f1aban nuestros legionarios cuando estaban en las trincheras pensando que les ayudar\u00edan en el frente si ca\u00edan heridos, o luego en el campamento les servir\u00edan un vasito de vino pele\u00f3n y ofrecer\u00edan un poco de su amor. En ocasiones se superpon\u00edan dos de estos calificativos o incluso los tres, resultando dif\u00edcil diferenciar hasta d\u00f3nde se ejerc\u00eda s\u00f3lo como cantinera, legionaria o barragana. En cualquier caso, lo que a continuaci\u00f3n menciono no tiene ning\u00fan sentido peyorativo, todo lo contrario, se trata de un reconocimiento a un apoyo moral muy merecido que ellas ejercieron para aquellos legionarios de la VII y VIII en tiempos de guerra. Veamos en primer lugar c\u00f3mo nos describen a las <i>cantineras<\/i>:<\/p>\n<blockquote>\n<blockquote>\n<p align=\"JUSTIFY\">\u00abNo obstante, haberse popularizado en los sainetes este tipo de mujer, en verdad no debieron adjudicarle el denominador de <i>cantineras, <\/i>ya que de todo ten\u00edan menos de ello. Este nombre solo cab\u00eda darle a quienes establec\u00edan en un local la venta de bebidas. Al fundarse la Legi\u00f3n y constituirse el campamento general en Dar-Riffien, afluyeron a \u00e9l infinidad de aventureros de uno y otro sexo que ve\u00edan en la prodigalidad de aquellos hombres un nuevo <i>Eldorado<\/i> que era preciso explotar. As\u00ed nacieron los <i>cantineros y cantineras<\/i>, hombres y mujeres incapaces de soportar ninguna disciplina ni rudo trabajo, que escog\u00edan aquel comercio con la esperanza bien fundada de ping\u00fces beneficios. Eran como el caracol. Llevaban su establecimiento a cuestas, transport\u00e1ndolo a lomos de una caballer\u00eda. Tan pronto las fuerzas acampaban, como por arte de magia aparec\u00edan en las proximidades del vivac con su tenderete de lonas y su mostrador, constituido \u00e9ste por los propios cajones en que transportaba la mercanc\u00eda. Entre tales mercaderes no pod\u00edan faltar los <i>ind\u00edgenas<\/i>, que, con sus teteras y dem\u00e1s admin\u00edculos, montaban tambi\u00e9n sus <i>chabolas <\/i>para expender el rico <i>tai<\/i> a perra gorda el vaso.<\/p>\n<p align=\"JUSTIFY\">Con tres paquetes de velas, unas cajas de <i>cigarros bastos<\/i>, unas <i>latas de conservas<\/i> mal conservadas y unos cuantos kilos de <i>vino en polvo<\/i>, se pasaba de simple cantinero a potentado. El cantinero era algo m\u00e1s simp\u00e1tico y distinto que el negociante, al que no hab\u00eda quien separase de las poblaciones. Aqu\u00e9l empezaba su trabajo acompa\u00f1ando a las tropas, con el riesgo consiguiente de que una bala cerrase su comercio a media puerta. Si la venta era prospera, alquilaba un caballejo y con \u00e9l recorr\u00eda las posiciones, intern\u00e1ndose algunas veces en las propias l\u00edneas enemigas. Era frecuente en Marruecos encontrar hombres de \u00e9stos tendidos en un charco de sangre en mitad de un camino, al que los moros hab\u00edan quitado, adem\u00e1s de la vida, sus provisiones y cabalgadura. Del alquiler del caballo se ascend\u00eda a la posesi\u00f3n de una peque\u00f1a tienda en el campamento, hecha con cajones de cerveza y chapas arrancadas de latas de petr\u00f3leo. De cantinero de posici\u00f3n no era dif\u00edcil llegar a provisionista del Ej\u00e9rcito, con magnifica tienda abierta en un campamento general.<\/p>\n<p align=\"JUSTIFY\">De entre todo el elemento que segu\u00eda a las Banderas legionarias, merecen especial atenci\u00f3n las mujeres que de ignoradas procedencias se incorporaban voluntariamente a las filas legionarias. Para poder justificar su presencia se amancebaban con un legionario, hecho \u00e9ste que les permit\u00eda seguir a su <i>hombre.<\/i> Lo original del caso era que no se erig\u00edan s\u00f3lo en servidoras de sus respectivos amantes, sino que ampliaban sus atenciones y cuidados a todos los legionarios, a modo de <i>cantineras<\/i> o <i>enfermeras. <\/i>En los combates se las ve\u00eda deambular entre las guerrillas y atender sol\u00edcitas a los heridos, suministr\u00e1ndoles la copa de co\u00f1ac, el vaso de vino o el cigarrillo, ayudando eficazmente a sanitarios y camilleros\u00bb.<\/p>\n<p><b><\/b><\/p><\/blockquote>\n<p><b><\/b><\/p><\/blockquote>\n<p align=\"JUSTIFY\">Legionarias y barraganas: amor de pago<\/p>\n<p align=\"JUSTIFY\">Se ha hablado de las cantineras en elogio de los heroicos e inapreciables servicios que con su desinter\u00e9s y desprecio al peligro prestaban a los legionarios que luchaban sobre este candente suelo africano bajo un sol m\u00e1s inclemente que el enemigo; pero hab\u00eda otras mujeres \u00a1pobrecitas! de las cuales nadie se ha interesado en ponderar, por una mal entendida hipocres\u00eda, los merecimientos de su cometido, que, aunque no llegaban a alcanzar precisamente proporciones heroicas, desempe\u00f1aban, sin embargo, oficio tal, que si era muy necesario en toda rep\u00fablica bien organizada, a\u00fan lo era m\u00e1s, much\u00edsimo m\u00e1s, en un campamento donde sol\u00eda ocurrir que, por las necesidades de la guerra, cientos o miles de hombres viv\u00edan, durante muchos meses seguidos, como lobos, aislados del mundo y sin otra sociedad que la del trato entre ellos mismos. El <i>fundador<\/i>, hombre de mundo, inteligencia comprensiva y abierta a todos los requerimientos de necesidades del legionario, toleraba la convivencia con sus tropas de algunas mujeres que por su esp\u00edritu de sacrificio y alg\u00fan dinero se encargaban de sostener en sus verdaderos cauces los instintos del hombre al servicio del inter\u00e9s de la especie, de la Patria y de la moral.<\/p>\n<blockquote>\n<blockquote>\n<p align=\"JUSTIFY\">\u00ab<i>Las legionarias<\/i>, as\u00ed las describe un legionario en la <i>Legi\u00f3n que vive<\/i>, viv\u00edan en los campamentos de la Legi\u00f3n, en peque\u00f1as tiendas de sacos o lonas de deshecho, denominadas <i>chavolas. <\/i>Unas lavaban ropas por m\u00f3dico estipendio. Otras cos\u00edan y arreglaban los trajes de almac\u00e9n, dej\u00e1ndolos casi a la medida de sus propietarios. Otras montaban peque\u00f1os establecimientos de bebidas, muy concurridos siempre, porque los legionarios gustaban de ser servidos por manos femeninas, y otras dejaban florecer en el dintel de sus chavolas el semi-marchito crisantemo del amor mercenario. Algunas vinieron siguiendo a sus maridos, quien sabe a trav\u00e9s de qu\u00e9 odisea dolorosa y tr\u00e1gica, las dem\u00e1s se unieron a sus hombres, si no can\u00f3nicamente, por lo menos sacrificadas por una religi\u00f3n de sufrimiento y de hero\u00edsmo. Com\u00edan el pan de la Legi\u00f3n y beb\u00edan su vino. Segu\u00edan sus vicisitudes, alegr\u00e1ndose con sus glorias y sufriendo con sus dolores. Ellas conoc\u00edan a los Jefes, a todos los h\u00e9roes, a todos los m\u00e1rtires, y hablando de ellos sus ojos se iluminaban y sus labios temblaban de emoci\u00f3n y respeto.<\/p>\n<p align=\"JUSTIFY\">Comentaban los grandes combates, las ingentes haza\u00f1as, los hechos gloriosos con singular delectaci\u00f3n, agrand\u00e1ndolos con su voladora fantas\u00eda. Ellas eran las que visitaban a los enfermos y los heridos llev\u00e1ndoles con el consuelo de unas palabras cari\u00f1osas, la caricia que en el infierno de la fiebre era como claro arroyuelo murmurador. Y ellas, en fin, eran las que en los d\u00edas malos, en los d\u00edas que el enemigo fue m\u00e1s certero y cayeron muchos legionarios, les acompa\u00f1aban, les lavaban y vest\u00edan, rezaban por ellos y encontraban siempre unas flores silvestres con que hacer una alfombra perfumada sobre la tierra que cubr\u00eda a los ca\u00eddos&#8230;<\/p>\n<p align=\"JUSTIFY\">Vedlas en las marchas, unas a pie, otras encaramadas en los borricos portadores de su humilde ajuar, siguiendo a la Bandera. Vedlas en los d\u00edas de combate subir a las alturas del campamento-base, donde se divisa el campo de acci\u00f3n. Vedlas, m\u00e1s tarde, esperar los convoyes de bajas, charlar con los heridos agobi\u00e1ndoles a preguntas, levantar temerosas y vacilantes la tela que cubre los rostros de los muertos, en una duda de tremenda emotividad. Y vedlas tambi\u00e9n, en los d\u00edas de fiesta legionaria, con los ojos brillantes de esa alegr\u00eda ficticia que dan unas porciones de alcohol, como se re\u00fanen en abigarrado conjunto, del que brota, como una flecha que fuera a clavarse en el cielo, el gemido de una copla andaluza.<\/p>\n<p align=\"JUSTIFY\">Est\u00e1is redimidas y nadie ha de pagaros lo mucho que hac\u00e9is llevando hasta los corazones legionarios algo de la suave emoci\u00f3n del cari\u00f1o de la hermana, de la esposa, de la madre. Las <i>legionarias<\/i>, si no llegaron a obtener el t\u00edtulo de benem\u00e9ritas de la Patria, alcanzaron la consideraci\u00f3n oficial figurando en las n\u00f3minas de los Tercios. Cuando fui al campamento del <i>Zoco El Arb\u00e1a<\/i> \u00a1parece que fue ayer! me vi enormemente sorprendido al hallar unas alegres y comedidas muchachas, a las cuales, m\u00e1s que por otra cosa, se las tomar\u00eda por obreritas en menesteres de enfermeras o de costura. Tal es la vida que hacen en el campamento, vida que se desliza tranquila y aplicable en el pleno y absoluto y sedante contacto con la naturaleza, que no inspira otros deseos que los deseos puros e infinitos de felicidad, de ternuras honestas.<\/p>\n<p align=\"JUSTIFY\">As\u00ed estas mujeres, que entre los legionarios son cada una de ellas como una rosa clavada en las arenas de una playa, hacen en nuestros campamentos, m\u00e1s que otro oficio, el de <i>costurera<\/i>, el de <i>enfermer\u00eda<\/i>; son nuestras <i>confidentes<\/i>; sus pechos rebosan de ternura o de pena; nos <i>prestan dinerito<\/i>, que pagamos siempre religiosamente; nos aconsejan mientras nos cosen un bot\u00f3n, y les consuelan cuando alguno tiene tristeza. \u00danicamente durante los primeros d\u00edas, que suceden al de la llegada de <i>una nueva,<\/i> tienen lugar los regocijantes <i>r\u00e9cords<\/i> de fabulosas cantidades ganadas en pocas horas. Entonces es cuando en las inmediaciones de la tienda de campa\u00f1a que ellas ocupan se ve, a trav\u00e9s de las discretas y misteriosas sombras de la noche, el largo desfile de hombres que aguardan su turno para prosternarse ante el altar de la diosa hija de J\u00fapiter\u00bb.<\/p>\n<\/blockquote>\n<\/blockquote>\n<p align=\"JUSTIFY\"><i><span style=\"font-family: 'Trebuchet MS'; font-size: large;\">Legionarias<\/span><\/i><span style=\"font-family: 'Trebuchet MS'; font-size: large;\"> famosas de los primeros a\u00f1os de la Legi\u00f3n lo fueron Rosario, Juana <i>la cuerpo bueno<\/i>, Rita <i>la dama Juana<\/i>, Lola <i>la chata<\/i>, Huelvana, Remedios, Rubia, Artillera, Vicenta, Mercedes, Gitanilla, Roselta&#8230; Entre los primeros alistados se present\u00f3 un aspirante acompa\u00f1ado de su mujer y de seis hijos. El Teniente Coronel Mill\u00e1n Astray, enterado de ello y en la situaci\u00f3n que quedar\u00edan estos, pidi\u00f3 a la esposa que disuadiera a su marido en sus deseos de alistarse en el Tercio de Extranjeros. Y ella respondi\u00f3: \u00abno dir\u00e9 yo a mi marido se quede o se marche, a \u00e9l corresponde decirlo. Hasta donde pueda y me deje, le acompa\u00f1ar\u00e9. A donde no pueda ir lo seguir\u00e9 con la vista, y despu\u00e9s con el pensamiento\u00bb.<\/span><\/p>\n<p align=\"JUSTIFY\">Iban a las marchas tocadas con el chambergo, siguiendo a las Banderas. Sub\u00edan al campo de la acci\u00f3n&#8230;, llegando y estando entre sus legionarios dedicadas por entero a su misi\u00f3n, con heroica abnegaci\u00f3n y con riesgo de su propia existencia. Consegu\u00edan el alivio y consuelo de los heridos, disputando a la muerte algunas vidas. Quer\u00edan de veras al Tercio de Extranjeros, y se desviv\u00edan por atender a los legionarios lo mismo en el campamento que en el combate, enardeci\u00e9ndoles con su sereno ejemplo de valor y virtudes.<\/p>\n<p align=\"JUSTIFY\">Otra cosa distinta fueron las <i>barraganas.<\/i> Llegaron a ser cosa tan necesarias en los antiguos Ej\u00e9rcitos, que m\u00e1s de una vez se pens\u00f3 en incluirlas en la plantilla de aquellos Tercios espa\u00f1oles de Flandes que no quer\u00edan prescindir del amor en la guerra, para evitar otros males mayores. Pero la <i>barragana<\/i> en el Tercio de Extranjeros fue simplemente la mujer p\u00fablica que serv\u00eda a uno o varios legionarios sus raciones de amor, y que dejaba su choza del campamento para seguir a las tropas en todos los trances de la guerra. Exist\u00edan claro est\u00e1, diversas clases y jerarqu\u00edas. Las hab\u00eda que ten\u00edan choza propia, con una tiendecita, y vend\u00edan al mismo tiempo <i>amor y tabaco<\/i>.<\/p>\n<p align=\"JUSTIFY\">Sus amigos legionarios por la cuenta que les tra\u00eda les levantaban sus refugios. Pero el tipo m\u00e1s generalizado era la cl\u00e1sica pupila de la mal llamada cantina, que ven\u00eda a ser, con m\u00e1s o menos motivo, una casa de lenocinio. Algunas, hab\u00edan nacido al oficio al mismo tiempo que la Legi\u00f3n. De lo \u00fanico que presum\u00edan era de lo que no hab\u00edan tenido nunca, de marido, o de hallarse casadas por <i>detr\u00e1s<\/i> de la Iglesia.<\/p>\n<p align=\"JUSTIFY\">Pero lo m\u00e1s admirable de toda esta fauna amorosa era su noble y generoso desprendimiento y su conducta abnegada en la guerra, al igual que las <i>cantineras<\/i> <i>del<\/i> <i>vino<\/i> <i>pele\u00f3n<\/i>, o las <i>legionarias adjuntas<\/i> a su hombre. Era digno el verlas seguir el paso azaroso y violento de las columnas en los cambios definitivos de campamento, con el pintoresco ajuar sobre sus espaldas, o tiradas en los carros de la impedimenta, entre b\u00e1rtulos y equipajes de las Banderas. Ellas practicaban la caridad a su modo, pues en cada hombre que ca\u00eda en sus brazos iban dejando algo de su coraz\u00f3n.<\/p>\n<p align=\"JUSTIFY\">Los festejos del 20 de septiembre<\/p>\n<p align=\"JUSTIFY\">Desconozco como se celebraba el d\u00eda del aniversario de la fundaci\u00f3n de la Legi\u00f3n durante los primeros a\u00f1os, en plena guerra de Marruecos. Cierto es que en la <i>cuna<\/i>, <i>Dar Riffien<\/i>, permanec\u00eda una guarnici\u00f3n <i>administrativa y de instrucci\u00f3n de reclutas<\/i>, junto con alguna Bandera que rotativamente estaba <i>de descanso<\/i>, que posiblemente de alg\u00fan modo conmemorar\u00edan el 20 de septiembre. Los <i>disfraces<\/i> y <i>charangas<\/i> que han permanecido hasta nuestros d\u00edas probablemente tengan sus or\u00edgenes en los <i>carnavales<\/i> y celebraci\u00f3n de la <i>Patrona de Infanter\u00eda<\/i>. En cualquier caso \u00e9sta era tambi\u00e9n una buena forma de divertirse en la retaguardia para aquellos que el 20 de septiembre no se encontraban combatiendo.<\/p>\n<p align=\"JUSTIFY\">As\u00ed, por ejemplo, 17 de febrero de 1922, en la Orden de La Legi\u00f3n, dada en el campamento de Dar Drius durante la permanencia en el mismo del Teniente Coronel Mill\u00e1n Astray, se publicaba la siguiente prevenci\u00f3n: \u00abDispuesto por Su Excelencia que el pr\u00f3ximo d\u00eda 26, primer d\u00eda de <i>carnaval<\/i>, se celebren festejos en los campamentos y que a ellos asistan los Cuerpos que lo deseen, presentando los n\u00fameros de <i>festejos<\/i> que prefieran para poder optar a tres premios en met\u00e1lico que se conceder\u00e1n. Espero de la alegr\u00eda, buen gusto y esp\u00edritu de la Legi\u00f3n que las Banderas se esforzar\u00e1n, empleando a los legionarios de buen humor, a dar la mayor brillantez al acto, y yo, por mi parte, ver\u00e9 con satisfacci\u00f3n que la Legi\u00f3n lo tome con el mayor inter\u00e9s y tambi\u00e9n ofrezco premios, significando que ver\u00e9 con gusto no sean murgas gaditanas, por ser un tema demasiado acabado e impropio de la originalidad de la Legi\u00f3n. En cambio, <i>los disfraces y comparsas me satisfacen mucho<\/i>. Encarezco a los se\u00f1ores Capitanes el que animen a sus legionarios para este acto\u00bb.<\/p>\n<p align=\"JUSTIFY\">Por su parte, me consta que en 1923 se conmemor\u00f3 en Riffien el aniversario y que despu\u00e9s del acto puramente militar del 20 de septiembre de 1923, di\u00f3 comienzo un pintoresco desfile de carrozas de ingenio t\u00edpicamente legionario; en \u00e9l, en momentos de descanso, las distintas unidades compitieron en arte, gracia e ingenio para, sobre motivos alusivos, manifestar la habilidad y el buen humor de sus hombres. Junto con las carrozas pasaron ante el p\u00fablico jinetes y hombres a pie con curiosos atuendos y portando carteles con frases y leyendas que despertaban tan pronto el inter\u00e9s como la hilaridad de los asistentes. Se vieron <i>carrozas<\/i> con los lemas <i>el agua de Dar Drius<\/i>, <i>la murga<\/i>, <i>el dios Baco<\/i>, <i>la cuna de la Legi\u00f3n<\/i>, <i>arrastrando ca\u00f1ones<\/i>, <i>me estoy matando<\/i> y <i>el Credo Legionario<\/i>, y entre ellos, jinetes <i>disfrazados<\/i> de piel roja, hombres negros, a pie una falsa mora, un esquimal y otros pintorescos disfraces. El paso de toda la abigarrada caravana fue acogido por el p\u00fablico unas veces con inter\u00e9s, otras con regocijo y siempre con el aplauso de aprobaci\u00f3n. Si todo esto ocurr\u00eda en 1.923, cabe suponer que en el 25 y 26, cuando se crearon la VII y VIII Banderas este tipo de festejos ya constitu\u00edan una tradici\u00f3n, tradici\u00f3n que ir\u00eda en aumento a partir de 1.927, una vez finalizada la guerra y que ha perdurado hasta nuestros d\u00edas en forma de casetas, charangas y festivales.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ANTECEDENTES: LA VII Y VIII EN LA 2\u00aa LEGION EN EL FRENTE Y EN LA RETAGUARDIA Las Especialidades: del granadero al camillero Y del estilo y la forma de vivir del legionario pasamos al modo de combatir en el frente y de divertirse en la retaguardia. Al igual que ocurre ahora, entonces tambi\u00e9n exist\u00edan especialistas [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"ocean_front_end_style_editor":"no","ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","footnotes":""},"class_list":["post-168","page","type-page","status-publish","hentry","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Frente y Retaguardia -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/amigosdeltercertercio.com\/web\/frente-y-retaguardia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Frente y Retaguardia -\" \/>\n<meta property=\"og:description\" content=\"ANTECEDENTES: LA VII Y VIII EN LA 2\u00aa LEGION EN EL FRENTE Y EN LA RETAGUARDIA Las Especialidades: del granadero al camillero Y del estilo y la forma de vivir del legionario pasamos al modo de combatir en el frente y de divertirse en la retaguardia. Al igual que ocurre ahora, entonces tambi\u00e9n exist\u00edan especialistas [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/amigosdeltercertercio.com\/web\/frente-y-retaguardia\/\" \/>\n<meta property=\"article:modified_time\" content=\"2015-04-25T13:52:23+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"23 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/amigosdeltercertercio.com\\\/web\\\/frente-y-retaguardia\\\/\",\"url\":\"https:\\\/\\\/amigosdeltercertercio.com\\\/web\\\/frente-y-retaguardia\\\/\",\"name\":\"Frente y Retaguardia -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amigosdeltercertercio.com\\\/web\\\/#website\"},\"datePublished\":\"2014-04-11T16:14:39+00:00\",\"dateModified\":\"2015-04-25T13:52:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/amigosdeltercertercio.com\\\/web\\\/frente-y-retaguardia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/amigosdeltercertercio.com\\\/web\\\/frente-y-retaguardia\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/amigosdeltercertercio.com\\\/web\\\/frente-y-retaguardia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/amigosdeltercertercio.com\\\/web\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Frente y Retaguardia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/amigosdeltercertercio.com\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/amigosdeltercertercio.com\\\/web\\\/\",\"name\":\"\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/amigosdeltercertercio.com\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Frente y Retaguardia -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/amigosdeltercertercio.com\/web\/frente-y-retaguardia\/","og_locale":"es_ES","og_type":"article","og_title":"Frente y Retaguardia -","og_description":"ANTECEDENTES: LA VII Y VIII EN LA 2\u00aa LEGION EN EL FRENTE Y EN LA RETAGUARDIA Las Especialidades: del granadero al camillero Y del estilo y la forma de vivir del legionario pasamos al modo de combatir en el frente y de divertirse en la retaguardia. Al igual que ocurre ahora, entonces tambi\u00e9n exist\u00edan especialistas [&hellip;]","og_url":"https:\/\/amigosdeltercertercio.com\/web\/frente-y-retaguardia\/","article_modified_time":"2015-04-25T13:52:23+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"23 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/amigosdeltercertercio.com\/web\/frente-y-retaguardia\/","url":"https:\/\/amigosdeltercertercio.com\/web\/frente-y-retaguardia\/","name":"Frente y Retaguardia -","isPartOf":{"@id":"https:\/\/amigosdeltercertercio.com\/web\/#website"},"datePublished":"2014-04-11T16:14:39+00:00","dateModified":"2015-04-25T13:52:23+00:00","breadcrumb":{"@id":"https:\/\/amigosdeltercertercio.com\/web\/frente-y-retaguardia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/amigosdeltercertercio.com\/web\/frente-y-retaguardia\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/amigosdeltercertercio.com\/web\/frente-y-retaguardia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/amigosdeltercertercio.com\/web\/"},{"@type":"ListItem","position":2,"name":"Frente y Retaguardia"}]},{"@type":"WebSite","@id":"https:\/\/amigosdeltercertercio.com\/web\/#website","url":"https:\/\/amigosdeltercertercio.com\/web\/","name":"","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/amigosdeltercertercio.com\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/amigosdeltercertercio.com\/web\/wp-json\/wp\/v2\/pages\/168","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amigosdeltercertercio.com\/web\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/amigosdeltercertercio.com\/web\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/amigosdeltercertercio.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amigosdeltercertercio.com\/web\/wp-json\/wp\/v2\/comments?post=168"}],"version-history":[{"count":3,"href":"https:\/\/amigosdeltercertercio.com\/web\/wp-json\/wp\/v2\/pages\/168\/revisions"}],"predecessor-version":[{"id":3837,"href":"https:\/\/amigosdeltercertercio.com\/web\/wp-json\/wp\/v2\/pages\/168\/revisions\/3837"}],"wp:attachment":[{"href":"https:\/\/amigosdeltercertercio.com\/web\/wp-json\/wp\/v2\/media?parent=168"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}